{"id":85,"date":"2020-01-13T11:08:58","date_gmt":"2020-01-13T11:08:58","guid":{"rendered":"https:\/\/demosites.io\/web-agency\/?page_id=5"},"modified":"2023-03-11T11:23:20","modified_gmt":"2023-03-11T11:23:20","slug":"digier","status":"publish","type":"page","link":"https:\/\/digier.erasmus.site\/pl\/","title":{"rendered":"STRONA DOMOWA"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"85\" class=\"elementor elementor-85\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e785a1 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"6e785a1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-93529e5\" data-id=\"93529e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34de459 elementor-widget elementor-widget-heading\" data-id=\"34de459\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DigiER - Digital Transborders Entrepreneurship Readiness<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa41038 elementor-widget elementor-widget-text-editor\" data-id=\"aa41038\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Numer projektu <\/strong>: 2020 &#8211; 1 &#8211; PL 01 &#8211; KA226 &#8211; VET &#8211; 096054<br \/><strong>Czas trwania projektu :<\/strong> 01.05.2021 &#8211; 30.04.2023<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e265486 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e265486\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e4dd889\" data-id=\"e4dd889\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a32c0d elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"9a32c0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"\/#about\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DOWIED\u0179 SI\u0118 WI\u0118CEJ<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-014f7f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"014f7f5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3446043\" data-id=\"3446043\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9515e53 elementor-widget elementor-widget-menu-anchor\" data-id=\"9515e53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"about\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-009c666 elementor-widget elementor-widget-heading\" data-id=\"009c666\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O projekcie DigiER<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae47633 elementor-widget elementor-widget-text-editor\" data-id=\"ae47633\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><p><\/p><p>Rewolucja cyfrowa zmieni\u0142a spos\u00f3b, w jaki ludzie bawi\u0105 si\u0119, uzyskuj\u0105 dost\u0119p do informacji, komunikuj\u0105 si\u0119 i ucz\u0105. Aby sprosta\u0107 tym wyzwaniom projekt DigiER ma na celu pom\u00f3c dostawcom VET w u\u017cyciu technologii w nowy i innowacyjny spos\u00f3b, aby wspiera\u0107 M\u015aP w cyfrowej gotowo\u015bci do przedsi\u0119biorczo\u015bci transgranicznej. Jednocze\u015bnie, badamy mo\u017cliwo\u015bci znalezienia nowych metod pedagogicznych, aby sprosta\u0107 wyzwaniom XXI wieku, promowa\u0107 partnerskie uczenie si\u0119 pomi\u0119dzy systemami edukacji ponadnarodowej i katalizowa\u0107 rozw\u00f3j niezb\u0119dnych kompetencji transwersalnych, tj. rozwi\u0105zywanie problem\u00f3w, wsp\u00f3\u0142praca i kreatywno\u015b\u0107.<\/p><p>Projekt DigiER oferuje innowacyjne rozwi\u0105zania w zakresie rozwoju przedsi\u0119biorstw rozpoczynaj\u0105cych dzia\u0142alno\u015b\u0107. W ramach projektu DigiER opracowywane s\u0105 narz\u0119dzia oferuj\u0105ce nowe informacje i wiedz\u0119, kt\u00f3ra b\u0119dzie przekazywana za pomoc\u0105 narz\u0119dzi ICT. Metody proponowane przez projekt DigiER s\u0105 innowacyjne &#8211; chcemy wyposa\u017cy\u0107 ludzi w wiedz\u0119, umiej\u0119tno\u015bci i pom\u00f3c im w zdobyciu kompetencji w szczeg\u00f3\u0142owych kwestiach dotycz\u0105cych buowania start-up\u00f3w.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-176a472 elementor-widget elementor-widget-heading\" data-id=\"176a472\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cele<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f30ceb6 elementor-widget elementor-widget-text-editor\" data-id=\"f30ceb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Celem projektu DigiER jest podniesienie \u015bwiadomo\u015bci na temat efektywnej cyfrowej przedsi\u0119biorczo\u015bci transgranicznej w\u015br\u00f3d pracownik\u00f3w izb handlowych, agencji rozwoju regionalnego, w\u0142adz lokalnych i centr\u00f3w rozwoju przedsi\u0119biorczo\u015bci, ale tak\u017ce nauczycieli VET, trener\u00f3w i mentor\u00f3w.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc5449a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc5449a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62525c9\" data-id=\"62525c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-126f2e5 elementor-widget elementor-widget-heading\" data-id=\"126f2e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rezultaty Projektu<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc35bd9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc35bd9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-38c1700\" data-id=\"38c1700\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a528dc elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1a528dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t1: Przewodnik po strategiach cyfrowej przedsi\u0119biorczo\u015bci transgranicznej w \u015brodowisku biznesowym\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMateria\u0142 szkoleniowy DigiER sk\u0142ada si\u0119 z zaproponowanych rozdzia\u0142\u00f3w, kt\u00f3re s\u0105 postrzegane jako najbardziej wsp\u00f3\u0142czesne tytu\u0142y modu\u0142\u00f3w szkoleniowych.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34d5b3a\" data-id=\"34d5b3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b94c6a8 elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b94c6a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t2: Aplikacja mobilna DigiER dla przedsi\u0119biorc\u00f3w\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAplikacja mobilna DigiER zapewni spersonalizowane \u015bcie\u017cki szkoleniowe poprzez wst\u0119pne sprawdzenie wiedzy i \u015bwiadomo\u015bci na temat cyfrowej przedsi\u0119biorczo\u015bci transgranicznej w\u015br\u00f3d przedsi\u0119biorc\u00f3w i os\u00f3b rozpoczynaj\u0105cych dzia\u0142alno\u015b\u0107 gospodarcz\u0105. Aplikacja mobilna DigiER opracuje r\u00f3wnie\u017c spersonalizowan\u0105 strategi\u0119 dla przedsi\u0119biorc\u00f3w i startup\u00f3w, aby mogli oni zaj\u0105\u0107 si\u0119 s\u0142abymi punktami i wzmocni\u0107 swoje podej\u015bcie do cyfrowej przedsi\u0119biorczo\u015bci transgranicznej.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-254a1f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"254a1f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ba3bc1\" data-id=\"9ba3bc1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6bcde8 elementor-widget elementor-widget-heading\" data-id=\"a6bcde8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Partnerzy Projektu<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bf8521 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bf8521\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-50b7ca4\" data-id=\"50b7ca4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b19763 elementor-widget elementor-widget-image\" data-id=\"0b19763\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.rig.katowice.pl\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/rig.png\" class=\"attachment-large size-large wp-image-134\" alt=\"\" srcset=\"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/rig.png 300w, https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/rig-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f3a655c\" data-id=\"f3a655c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbfad74 elementor-widget elementor-widget-image\" data-id=\"fbfad74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.kainotomia.com.gr\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/kainotomia.png\" class=\"attachment-large size-large wp-image-135\" alt=\"\" srcset=\"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/kainotomia.png 300w, https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/kainotomia-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c6a9416\" data-id=\"c6a9416\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc94a23 elementor-widget elementor-widget-image\" data-id=\"dc94a23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cwep.eu\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/cwep.png\" class=\"attachment-large size-large wp-image-136\" alt=\"\" srcset=\"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/cwep.png 300w, https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/cwep-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eef31e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eef31e3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-70ba3cf\" data-id=\"70ba3cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82df4d4 elementor-widget elementor-widget-image\" data-id=\"82df4d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.civicuk.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/civic.png\" class=\"attachment-large size-large wp-image-140\" alt=\"\" srcset=\"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/civic.png 300w, https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/civic-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-657e6bc\" data-id=\"657e6bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81a84df elementor-widget elementor-widget-image\" data-id=\"81a84df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.eng.gzs.si\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/gzs.png\" class=\"attachment-large size-large wp-image-142\" alt=\"\" srcset=\"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/gzs.png 300w, https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/gzs-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7745b90\" data-id=\"7745b90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ba707f elementor-widget elementor-widget-image\" data-id=\"5ba707f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.cciabn.ro\/webb\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/camera.png\" class=\"attachment-large size-large wp-image-172\" alt=\"\" srcset=\"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/camera.png 300w, https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/camera-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-81fa719 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"81fa719\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46155d8\" data-id=\"46155d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d8f1dc elementor-widget elementor-widget-spacer\" data-id=\"7d8f1dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DigiER &#8211; Digital Transborders Entrepreneurship Readiness Numer projektu : 2020 &#8211; 1 &#8211; PL 01 &#8211; KA226 &#8211; VET &#8211;&hellip;&nbsp;<a href=\"https:\/\/digier.erasmus.site\/pl\/\" rel=\"bookmark\">Dowiedz si\u0119 wi\u0119cej &raquo;<span class=\"screen-reader-text\">STRONA DOMOWA<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"neve_meta_sidebar":"full-width","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-85","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STRONA DOMOWA - DigiER Project<\/title>\n<meta name=\"description\" content=\"DigiER - Digital Transborders Entrepreneurship Readiness - Erasmus+ Project\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digier.erasmus.site\/pl\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STRONA DOMOWA - DigiER Project\" \/>\n<meta property=\"og:description\" content=\"DigiER - Digital Transborders Entrepreneurship Readiness - Erasmus+ Project\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digier.erasmus.site\/pl\/\" \/>\n<meta property=\"og:site_name\" content=\"DigiER Project\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DigierProject\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-11T11:23:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/rig.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/\",\"url\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/\",\"name\":\"STRONA DOMOWA - DigiER Project\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digier.erasmus.site\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digier.erasmus.site\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/rig.png\",\"datePublished\":\"2020-01-13T11:08:58+00:00\",\"dateModified\":\"2023-03-11T11:23:20+00:00\",\"description\":\"DigiER - Digital Transborders Entrepreneurship Readiness - Erasmus+ Project\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digier.erasmus.site\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/rig.png\",\"contentUrl\":\"https:\\\/\\\/digier.erasmus.site\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/rig.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"STRONA DOMOWA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/\",\"name\":\"DigiER Project\",\"description\":\"DigiER - Digital Transborders Entrepreneurship Readiness\",\"publisher\":{\"@id\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/#organization\",\"name\":\"DigiER - Digital Transborders Entrepreneurship Readiness\",\"url\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/digier.erasmus.site\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/DigiER-Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/digier.erasmus.site\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/DigiER-Logo.jpg\",\"width\":1123,\"height\":794,\"caption\":\"DigiER - Digital Transborders Entrepreneurship Readiness\"},\"image\":{\"@id\":\"https:\\\/\\\/digier.erasmus.site\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DigierProject\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/digier-digital-transborder-entrepreneurship-readiness\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STRONA DOMOWA - DigiER Project","description":"DigiER - Digital Transborders Entrepreneurship Readiness - Erasmus+ Project","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digier.erasmus.site\/pl\/","og_locale":"pl_PL","og_type":"article","og_title":"STRONA DOMOWA - DigiER Project","og_description":"DigiER - Digital Transborders Entrepreneurship Readiness - Erasmus+ Project","og_url":"https:\/\/digier.erasmus.site\/pl\/","og_site_name":"DigiER Project","article_publisher":"https:\/\/www.facebook.com\/DigierProject","article_modified_time":"2023-03-11T11:23:20+00:00","og_image":[{"url":"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/rig.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"8 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/digier.erasmus.site\/pl\/","url":"https:\/\/digier.erasmus.site\/pl\/","name":"STRONA DOMOWA - DigiER Project","isPartOf":{"@id":"https:\/\/digier.erasmus.site\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digier.erasmus.site\/pl\/#primaryimage"},"image":{"@id":"https:\/\/digier.erasmus.site\/#primaryimage"},"thumbnailUrl":"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/rig.png","datePublished":"2020-01-13T11:08:58+00:00","dateModified":"2023-03-11T11:23:20+00:00","description":"DigiER - Digital Transborders Entrepreneurship Readiness - Erasmus+ Project","breadcrumb":{"@id":"https:\/\/digier.erasmus.site\/pl\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/digier.erasmus.site\/pl\/"]]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/digier.erasmus.site\/pl\/#primaryimage","url":"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/rig.png","contentUrl":"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/12\/rig.png"},{"@type":"BreadcrumbList","@id":"https:\/\/digier.erasmus.site\/pl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/digier.erasmus.site\/pl\/"},{"@type":"ListItem","position":2,"name":"STRONA DOMOWA"}]},{"@type":"WebSite","@id":"https:\/\/digier.erasmus.site\/pl\/#website","url":"https:\/\/digier.erasmus.site\/pl\/","name":"DigiER Project","description":"DigiER - Digital Transborders Entrepreneurship Readiness","publisher":{"@id":"https:\/\/digier.erasmus.site\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digier.erasmus.site\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/digier.erasmus.site\/pl\/#organization","name":"DigiER - Digital Transborders Entrepreneurship Readiness","url":"https:\/\/digier.erasmus.site\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/digier.erasmus.site\/pl\/#\/schema\/logo\/image\/","url":"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/11\/DigiER-Logo.jpg","contentUrl":"https:\/\/digier.erasmus.site\/wp-content\/uploads\/2021\/11\/DigiER-Logo.jpg","width":1123,"height":794,"caption":"DigiER - Digital Transborders Entrepreneurship Readiness"},"image":{"@id":"https:\/\/digier.erasmus.site\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DigierProject","https:\/\/www.linkedin.com\/company\/digier-digital-transborder-entrepreneurship-readiness\/"]}]}},"_links":{"self":[{"href":"https:\/\/digier.erasmus.site\/pl\/wp-json\/wp\/v2\/pages\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digier.erasmus.site\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/digier.erasmus.site\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/digier.erasmus.site\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digier.erasmus.site\/pl\/wp-json\/wp\/v2\/comments?post=85"}],"version-history":[{"count":166,"href":"https:\/\/digier.erasmus.site\/pl\/wp-json\/wp\/v2\/pages\/85\/revisions"}],"predecessor-version":[{"id":1555,"href":"https:\/\/digier.erasmus.site\/pl\/wp-json\/wp\/v2\/pages\/85\/revisions\/1555"}],"wp:attachment":[{"href":"https:\/\/digier.erasmus.site\/pl\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}